{"id":4600,"date":"2019-07-10T10:17:45","date_gmt":"2019-07-10T15:17:45","guid":{"rendered":"https:\/\/enlacescorporativos.com\/?p=4600"},"modified":"2019-07-10T10:17:45","modified_gmt":"2019-07-10T15:17:45","slug":"dos-casos-explican-como-el-cambio-climatico-esta-provocando-el-sargazo","status":"publish","type":"post","link":"https:\/\/enlacescorporativos.com\/en\/2019\/07\/10\/dos-casos-explican-como-el-cambio-climatico-esta-provocando-el-sargazo\/","title":{"rendered":"Dos casos explican c\u00f3mo el cambio clim\u00e1tico est\u00e1 provocando el sargazo"},"content":{"rendered":"<div><img src='https:\/\/cdn.forbes.com.mx\/2018\/08\/sargazo-sectur.jpg' style='max-width:600px;' \/><\/p>\n<div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\">Forbes M\u00e9xico<\/a>.<br \/>\n <a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/dos-casos-explican-como-el-cambio-climatico-esta-provocando-el-sargazo\/\">Dos casos explican c\u00f3mo el cambio clim\u00e1tico est\u00e1 provocando el sargazo<\/a><\/p>\n<div><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/cdn.forbes.com.mx\/2018\/08\/sargazo-sectur.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" style=\"margin-bottom: 15px;\" srcset=\"https:\/\/cdn.forbes.com.mx\/2018\/08\/sargazo-sectur.jpg 1280w, https:\/\/cdn.forbes.com.mx\/2018\/08\/sargazo-sectur-300x169.jpg 300w, https:\/\/cdn.forbes.com.mx\/2018\/08\/sargazo-sectur-768x432.jpg 768w, https:\/\/cdn.forbes.com.mx\/2018\/08\/sargazo-sectur-1024x576.jpg 1024w, https:\/\/cdn.forbes.com.mx\/2018\/08\/sargazo-sectur-640x360.jpg 640w, https:\/\/cdn.forbes.com.mx\/2018\/08\/sargazo-sectur-320x180.jpg 320w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" data-full-size=\"https:\/\/cdn.forbes.com.mx\/2018\/08\/sargazo-sectur.jpg\" data-caption=\"Trabajadores limpian playas de sargazo (Foto: Sectur Quintana Roo)\" data-description=\"\" \/><\/div>\n<p>Lo que sabemos hasta el d\u00eda de hoy sobre el sargazo que ha llegado a M\u00e9xico es que es un alga que ha arribado a las costas principalmente de Quintana Roo. Para los investigadores, el cambio climatico es el causante de este problema.<\/p>\n<p>Para los profesores de la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM), Daniel Le\u00f3n y Jos\u00e9 Guadalupe Palacios, las grandes cantidades de sargazo que ha llegado a M\u00e9xico puede explicarse por el calentamiento global.<\/p>\n<p>\u201cTodo parece indicar que el calentamiento global del oc\u00e9ano est\u00e1 provocando corrientes que han hecho que los crecimientos del sargazo sean enviados hacia el sur y el Caribe, por lo que este fen\u00f3meno se ha visto en las costas de M\u00e9xico, Brasil, Costa Rica, y \u00c1frica, por mencionar algunas ubicaciones\u201d, explica el doctor en Ciencias por la UNAM, Daniel Le\u00f3n.<\/p>\n<p>El verano del 2015 ser\u00e1 recordado en Puerto Morelos, Quintana Roo, en la Riviera Maya como uno de los a\u00f1os en donde el cambio clim\u00e1tico se hizo presente.<\/p>\n<p>Ese verano, seg\u00fan datos publicados por la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica de Estados Unidos (NOAA, por sus siglas en ingl\u00e9s) se registraron los \u00edndices m\u00e1s altos de temperatura en las superficies terrestres y oce\u00e1nicas del planeta de los \u00faltimos 135 a\u00f1os.<\/p>\n<p>\u201cPor si fuera poco, toneladas de sargazo allanaron las costas del Caribe, ti\u00f1endo las playas de un color caf\u00e9 obscuro y emitiendo un olor f\u00e9tido (\u00e1cido sulfh\u00eddrico) debido a la descomposici\u00f3n de esta alga, causando la cancelaci\u00f3n de cientos de vuelos nacionales e internacionales y reservaciones en los hoteles, acarreando una gran p\u00e9rdida de la derrama econ\u00f3mica y de empleos fijos y temporales en la regi\u00f3n\u201d, dice el Programa de las Naciones Unidas para el Desarrollo (PNUD).<\/p>\n<p>El Caribe siempre ha tenido presencia de sargazo en sus costas, pero ese 2015 hubo un cambio dr\u00e1stico. Seg\u00fan investigadores de la Universidad de Galveston (Texas), un cambio en las corrientes marinas debido al aumento de la temperatura de los mares afect\u00f3 la distribuci\u00f3n del sargazo envi\u00e1ndolo en grandes cantidades a las costas del Caribe.<\/p>\n<p><strong>Te recomendamos:\u00a0<\/strong><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"HT2CnqwGGn\">\n<p><a href=\"https:\/\/www.forbes.com.mx\/hoteleros-en-riviera-maya-toman-medidas-para-no-perder-turistas-por-sargazo\/\">Hoteleros en Riviera Maya toman medidas para no perder turistas por sargazo<\/a><\/p>\n<\/blockquote>\n<p><iframe class=\"embed-responsive-item\"  title=\"&#8220;Hoteleros en Riviera Maya toman medidas para no perder turistas por sargazo&#8221; &#8212; Forbes M\u00e9xico\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.forbes.com.mx\/hoteleros-en-riviera-maya-toman-medidas-para-no-perder-turistas-por-sargazo\/embed\/#?secret=HT2CnqwGGn\" data-secret=\"HT2CnqwGGn\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/dos-casos-explican-como-el-cambio-climatico-esta-provocando-el-sargazo\/\">Dos casos explican c\u00f3mo el cambio clim\u00e1tico est\u00e1 provocando el sargazo<\/a><br \/>\n<a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/author\/forbes-staff\/\">Forbes Staff<\/a><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Forbes M\u00e9xico. Dos casos explican c\u00f3mo el cambio clim\u00e1tico est\u00e1 provocando el sargazo Lo que sabemos hasta el d\u00eda de hoy sobre el sargazo que ha llegado a M\u00e9xico es que es un alga que ha arribado a las costas principalmente de Quintana Roo. Para los investigadores, el cambio climatico es el causante de este [&hellip;]<\/p>","protected":false},"author":91,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4600","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/comments?post=4600"}],"version-history":[{"count":0,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4600\/revisions"}],"wp:attachment":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/media?parent=4600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/categories?post=4600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/tags?post=4600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}