{"id":4618,"date":"2019-07-10T12:11:27","date_gmt":"2019-07-10T17:11:27","guid":{"rendered":"https:\/\/enlacescorporativos.com\/?p=4618"},"modified":"2019-07-10T12:11:27","modified_gmt":"2019-07-10T17:11:27","slug":"urzua-deja-el-poder-a-raquel-buenrostro-para-hacer-todas-las-compras-del-gobierno","status":"publish","type":"post","link":"https:\/\/enlacescorporativos.com\/en\/2019\/07\/10\/urzua-deja-el-poder-a-raquel-buenrostro-para-hacer-todas-las-compras-del-gobierno\/","title":{"rendered":"Urz\u00faa deja el poder a Raquel Buenrostro para hacer todas las compras del gobierno"},"content":{"rendered":"<div><img src='https:\/\/cdn.forbes.com.mx\/2019\/01\/raquel-buenrostro-amlo.jpg' style='max-width:600px;' \/><\/p>\n<div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\">Forbes M\u00e9xico<\/a>.<br \/>\n <a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/urzua-deja-el-poder-a-raquel-buenrostro-para-hacer-compras-del-gobierno\/\">Urz\u00faa deja el poder a Raquel Buenrostro para hacer todas las compras del gobierno<\/a><\/p>\n<div><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/cdn.forbes.com.mx\/2019\/01\/raquel-buenrostro-amlo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" style=\"margin-bottom: 15px;\" srcset=\"https:\/\/cdn.forbes.com.mx\/2019\/01\/raquel-buenrostro-amlo.jpg 1280w, https:\/\/cdn.forbes.com.mx\/2019\/01\/raquel-buenrostro-amlo-300x169.jpg 300w, https:\/\/cdn.forbes.com.mx\/2019\/01\/raquel-buenrostro-amlo-768x432.jpg 768w, https:\/\/cdn.forbes.com.mx\/2019\/01\/raquel-buenrostro-amlo-1024x576.jpg 1024w, https:\/\/cdn.forbes.com.mx\/2019\/01\/raquel-buenrostro-amlo-640x360.jpg 640w, https:\/\/cdn.forbes.com.mx\/2019\/01\/raquel-buenrostro-amlo-320x180.jpg 320w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" data-full-size=\"https:\/\/cdn.forbes.com.mx\/2019\/01\/raquel-buenrostro-amlo.jpg\" data-caption=\"Raquel Buenrostro, oficial mayor de la SHCP, en la conferencia &quot;ma\u00f1anera&quot; del presidente L\u00f3pez Obrador. (Foto: Gobierno de M\u00e9xico)\" data-description=\"\" \/><\/div>\n<p>Unos d\u00edas antes de presentar su renuncia como secretario de Hacienda, Carlos Urz\u00faa le deleg\u00f3 a la Oficial Mayor, Raquel Buenrostro, la facultad legal para controlar de principio a fin las compras consolidadas del gobierno.<\/p>\n<p>El 8 de julio se public\u00f3 en el Diario Oficial de la Federaci\u00f3n (DOF) un acuerdo firmado el 4 de julio por el todav\u00eda secretario, con el que deleg\u00f3 a la Oficial Mayor \u00abla facultad de promover, dise\u00f1ar, elaborar, celebrar, suscribir y administrar los contratos marco, en t\u00e9rminos de los art\u00edculos 17 de la Ley de Adquisiciones (\u2026) para establecer los lineamientos para coordinar dicho procedimiento\u00bb.<\/p>\n<p>Con esto, la Oficial Mayor recibi\u00f3 facultades plenas para licitar y celebrar los contratos marco de las compras consolidadas del gobierno, una atribuci\u00f3n que era del secretario de Hacienda, de acuerdo con <a href=\"https:\/\/contralacorrupcion.mx\/urzua-delega-superfacultad-para-contrataciones-a-raquel-buenrostro-antes-de-renunciar-a-hacienda\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mexicanos Contra la Corrupci\u00f3n y la Impunidad<\/a> (MCCI).<\/p>\n<p>Hist\u00f3ricamente, estos contratos eran celebrados por las dependencias licitantes en coordinaci\u00f3n con la Secretar\u00eda de la Funci\u00f3n P\u00fablica, que era la encargada de realizar contratos marco \u2013en los que se acuerda previamente con los proveedores las especificaciones de los bienes o servicios a adquirir, as\u00ed como sus precios, la calidad y las condiciones.<\/p>\n<p>\u201cEsto cambi\u00f3 el 30 de noviembre de 2018, un d\u00eda antes de que tomara posesi\u00f3n la nueva administraci\u00f3n, cuando se entreg\u00f3 esta facultad al secretario de Hacienda mediante una reforma a la Ley Org\u00e1nica de la Administraci\u00f3n P\u00fablica Federal\u201d, seg\u00fan MCCI.<\/p>\n<p>En estos meses, la Oficial Mayor de Hacienda hab\u00eda sido la responsable de las compras consolidadas del gobierno, entre las que destaca la de medicamentos. Con este acuerdo, Buenrostro es ahora tambi\u00e9n la responsable legal.<\/p>\n<p>El acuerdo se\u00f1ala que el cambio fue \u00abcon la finalidad de procurar la mejor organizaci\u00f3n del trabajo y agilizar el despacho de los asuntos competencia de esta Secretar\u00eda, es necesario delegar en favor del Oficial Mayor las facultades que se indican\u00bb.<\/p>\n<p><strong>Te recomendamos:\u00a0<\/strong><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"ffC0Tk30Bz\">\n<p><a href=\"https:\/\/www.forbes.com.mx\/ligan-a-salinas-y-pena-en-caso-collado-los-senalan-como-duenos-de-caja-libertad\/\">Ligan a Salinas y Pe\u00f1a en caso Collado; los se\u00f1alan como due\u00f1os de Caja Libertad<\/a><\/p>\n<\/blockquote>\n<p><iframe class=\"embed-responsive-item\"  title=\"&#8220;Ligan a Salinas y Pe\u00f1a en caso Collado; los se\u00f1alan como due\u00f1os de Caja Libertad&#8221; &#8212; Forbes M\u00e9xico\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.forbes.com.mx\/ligan-a-salinas-y-pena-en-caso-collado-los-senalan-como-duenos-de-caja-libertad\/embed\/#?secret=ffC0Tk30Bz\" data-secret=\"ffC0Tk30Bz\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/urzua-deja-el-poder-a-raquel-buenrostro-para-hacer-compras-del-gobierno\/\">Urz\u00faa deja el poder a Raquel Buenrostro para hacer todas las compras del gobierno<\/a><br \/>\n<a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/author\/forbes-staff\/\">Forbes Staff<\/a><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Forbes M\u00e9xico. Urz\u00faa deja el poder a Raquel Buenrostro para hacer todas las compras del gobierno Unos d\u00edas antes de presentar su renuncia como secretario de Hacienda, Carlos Urz\u00faa le deleg\u00f3 a la Oficial Mayor, Raquel Buenrostro, la facultad legal para controlar de principio a fin las compras consolidadas del gobierno. El 8 de julio [&hellip;]<\/p>","protected":false},"author":91,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4618","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/comments?post=4618"}],"version-history":[{"count":0,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4618\/revisions"}],"wp:attachment":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/media?parent=4618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/categories?post=4618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/tags?post=4618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}