{"id":4630,"date":"2019-07-10T13:11:32","date_gmt":"2019-07-10T18:11:32","guid":{"rendered":"https:\/\/enlacescorporativos.com\/?p=4630"},"modified":"2019-07-10T13:11:32","modified_gmt":"2019-07-10T18:11:32","slug":"nuevas-habilidades-de-liderazgo-exigencia-2020","status":"publish","type":"post","link":"https:\/\/enlacescorporativos.com\/en\/2019\/07\/10\/nuevas-habilidades-de-liderazgo-exigencia-2020\/","title":{"rendered":"Nuevas habilidades de liderazgo, exigencia 2020"},"content":{"rendered":"<div><img src='https:\/\/cdn.forbes.com.mx\/2019\/03\/mujereslideres.jpg' style='max-width:600px;' \/><\/p>\n<div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\">Forbes M\u00e9xico<\/a>.<br \/>\n <a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/nuevas-habilidades-de-liderazgo-exigencia-2020\/\">Nuevas habilidades de liderazgo, exigencia 2020<\/a><\/p>\n<div><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/cdn.forbes.com.mx\/2019\/03\/mujereslideres.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" style=\"margin-bottom: 15px;\" srcset=\"https:\/\/cdn.forbes.com.mx\/2019\/03\/mujereslideres.jpg 1280w, https:\/\/cdn.forbes.com.mx\/2019\/03\/mujereslideres-300x169.jpg 300w, https:\/\/cdn.forbes.com.mx\/2019\/03\/mujereslideres-768x432.jpg 768w, https:\/\/cdn.forbes.com.mx\/2019\/03\/mujereslideres-1024x576.jpg 1024w, https:\/\/cdn.forbes.com.mx\/2019\/03\/mujereslideres-640x360.jpg 640w, https:\/\/cdn.forbes.com.mx\/2019\/03\/mujereslideres-320x180.jpg 320w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" data-full-size=\"https:\/\/cdn.forbes.com.mx\/2019\/03\/mujereslideres.jpg\" data-caption=\"Foto: Pexels\" data-description=\"\" \/><\/div>\n<p>Nos acercamos a la tercera d\u00e9cada del siglo XXI, la evoluci\u00f3n de las tareas profesionales y las condiciones de competencia depredadora, as\u00ed como los requerimientos de una nueva realidad de mercados, emprendedores, redes, grupos sociales y empresas diversificadas, multinivel y altamente tecnologizadas exigen nuevas habilidades, recursos y capacidades para estar vigente en el mercado laboral.<\/p>\n<p><strong>1)<\/strong> <strong>Comunicaci\u00f3n 360<\/strong>. No puedes triunfar sin manejar grandes, actuales y s\u00f3lidos recursos de comunicaci\u00f3n. Debes ser capaz de transmitir ideas de manera impactante; manejar grandes vol\u00famenes de informaci\u00f3n con una estructura, oportunidad, prioridad, sentido, relevancia y profundidad. Generar y administrar una vitalidad eficiente en las redes sociales, adaptarte a las audiencias globales, hacer presentaciones persuasivas, hablar en p\u00fablico con soltura y dominio. Redactar con precisi\u00f3n, congruencia, estilo, dicci\u00f3n, articulaci\u00f3n, riqueza de conceptos. Explotar al m\u00e1ximo la creatividad, libertad de dise\u00f1o, impacto, atracci\u00f3n.<\/p>\n<p>Manipular, convencer, persuadir, transmitir confianza, pasi\u00f3n, seguridad es parte de la selecci\u00f3n natural para destacar, evolucionar y avanzar en tu carrera. La competencia por los clientes requiere de vender y activar las emociones en idiomas y protocolos multiculturales.<\/p>\n<p><strong>\u00a02) Integraci\u00f3n vital<\/strong>. Saber c\u00f3mo establecer y mantener <a href=\"https:\/\/www.forbes.com.mx\/las-habilidades-que-un-lider-debe-desarrollar\/\" target=\"_blank\" rel=\"noopener noreferrer\">relaciones humanas<\/a> que estimulen un ambiente de trabajo productivo, coordinado y eficiente incluso no presencial es clave en estos tiempos. Ser capaz de mostrar tolerancia, respeto y saber ajustarse a ambientes multinacionales, horarios diferenciados y las modalidades de trabajo que implican viajar constantemente e interactuar con personas de diferentes ideolog\u00edas, religiones, pa\u00edses y formas de hacer negocios.<\/p>\n<p>Nada de prejuicios ni reduccionismos, existe una gran diversidad de comportamientos, protocolos de trato y formatos de socializaci\u00f3n. Acoplarse a un estilo de vida multitarea en ambientes virtuales colaborativos y plataformas de tareas en tiempo real. La clave es lograr cooperaci\u00f3n, coordinaci\u00f3n, rendimiento e interacci\u00f3n eficiente a distancia.<\/p>\n<p>Conferencias, intercambios, experiencias en un mundo globalizado donde la evoluci\u00f3n es incre\u00edblemente r\u00e1pida, asimilar los grandes cambios en tiempo real es un activo imprescindible para quien busca destacar y liderar en estos tiempos.<\/p>\n<p><strong>3) Transformaci\u00f3n humana<\/strong>. Las empresas requieren profesionales con actitud de cambio, hambre de progreso, superaci\u00f3n de barreras y una sana ambici\u00f3n altamente competitiva. Saben que cada d\u00eda requieren de grandes transformaciones internas y que nadie puede estancarse en un mercado tan competitivo, por lo tanto, en cada unidad de trabajo se requiere de l\u00edderes que impulsen y promuevan estos cambios de manera cotidiana.<\/p>\n<p>Sobre este tema en particular se ha dicho mucho y se han descrito miles de formas que puede asumir este proceso lo relevante es la capacidad para dirigir grupos humanos hacia metas comunes, con un sentido de motivaci\u00f3n, responsabilidad y disciplina natural no impuesto, que haga surgir lo mejor de cada uno y que les provea de un sentido de triunfo, integraci\u00f3n y realizaci\u00f3n.<\/p>\n<p><strong>4) Responsabilidad social<\/strong>. Con mayor frecuencia, las empresas buscan reforzar sus controles de reclutamiento por el incremento de conductas no deseadas entre sus prospectos. Existen alertas sobre malos h\u00e1bitos, adicciones, problemas de socializaci\u00f3n, falta de compromiso, pero particularmente sobre la violencia y corrupci\u00f3n.<\/p>\n<p>Los esc\u00e1ndalos personales que se vuelven tendencia, una <em>selfie<\/em>, videos, grabaciones o memes que exhiben pr\u00e1cticas il\u00edcitas o conductas inapropiadas dentro de los centros de trabajo, demandas, denuncias y filtraciones a los medios, todo esto afecta a la empresa, sus marcas, sus servicios, por supuesto cuesta dinero y muchas veces el da\u00f1o suele ser muy grave en t\u00e9rminos de mercado, clientes y reputaci\u00f3n.<\/p>\n<p>La confianza de los p\u00fablicos es clave, para evitar problemas, las empresas tienen que invertir en nuevos materiales, procesos, tecnolog\u00edas y materiales, pero ante todo, en el monitoreo y control de conductas, campa\u00f1as internas y hasta el involucramiento del personal para evitar incidencias que se viralicen y afecten la imagen y reputaci\u00f3n de productos, marcas y\/o servicios.<\/p>\n<p><strong>5) Progresi\u00f3n competitiva<\/strong>. Car\u00e1cter y visi\u00f3n se requieren cuando la vida est\u00e1 al borde, las operaciones se hacen en milisegundos y la tecnolog\u00eda mueve billones de mercanc\u00edas a todos los rincones del mundo. No hay lugar ni para la mediocridad y el conformismo; la vida laboral requiere de un sentido de emoci\u00f3n y motivaci\u00f3n constante en todo lo que haces.<\/p>\n<p>Hoy es el tiempo de los emprendedores, de los que vencen las resistencias, los l\u00edmites y que hacen de cada espaci\u00f3 un centro de innovaci\u00f3n dentro de una empresa. No te reserves nada, mejora tu desempe\u00f1o y dale a tu vida laboral un sentido de progreso permanente.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Contact<\/strong>:<\/p>\n<p>Correo:\u00a0contacto@capitolcoms.com<\/p>\n<p>Twitter:\u00a0<a href=\"https:\/\/twitter.com\/CapitolCComm\" target=\"_blank\" rel=\"noopener noreferrer\">@CapitolCComm<\/a><\/p>\n<p>Facebook:\u00a0<a href=\"https:\/\/www.facebook.com\/CapitolCC\" target=\"_blank\" rel=\"noopener noreferrer\">Capitol Consulting &amp; Communication S.C.<\/a><\/p>\n<p>P\u00e1gina web:\u00a0<a href=\"http:\/\/www.capitolcoms.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Capitol Consulting &amp; Communication<\/a><\/p>\n<p><em>Las opiniones expresadas son s\u00f3lo responsabilidad de sus autores y son completamente independientes de la postura y la l\u00ednea editorial de\u00a0<strong>Forbes M\u00e9xico<\/strong>.<\/em><\/p>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/nuevas-habilidades-de-liderazgo-exigencia-2020\/\">Nuevas habilidades de liderazgo, exigencia 2020<\/a><br \/>\n<a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/author\/alfredo-paredes\/\">Alfredo Paredes<\/a><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Forbes M\u00e9xico. Nuevas habilidades de liderazgo, exigencia 2020 Nos acercamos a la tercera d\u00e9cada del siglo XXI, la evoluci\u00f3n de las tareas profesionales y las condiciones de competencia depredadora, as\u00ed como los requerimientos de una nueva realidad de mercados, emprendedores, redes, grupos sociales y empresas diversificadas, multinivel y altamente tecnologizadas exigen nuevas habilidades, recursos y [&hellip;]<\/p>","protected":false},"author":91,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4630","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/comments?post=4630"}],"version-history":[{"count":0,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4630\/revisions"}],"wp:attachment":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/media?parent=4630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/categories?post=4630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/tags?post=4630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}