{"id":4634,"date":"2019-07-10T13:21:22","date_gmt":"2019-07-10T18:21:22","guid":{"rendered":"https:\/\/enlacescorporativos.com\/?p=4634"},"modified":"2019-07-10T13:21:22","modified_gmt":"2019-07-10T18:21:22","slug":"concacaf-cambia-eliminatoria-mundialista-mexico-jugaria-menos-partidos","status":"publish","type":"post","link":"https:\/\/enlacescorporativos.com\/en\/2019\/07\/10\/concacaf-cambia-eliminatoria-mundialista-mexico-jugaria-menos-partidos\/","title":{"rendered":"Concacaf cambia eliminatoria mundialista; M\u00e9xico jugar\u00eda menos partidos"},"content":{"rendered":"<div><img src='https:\/\/cdn.forbes.com.mx\/2019\/03\/seleccion-mexicana-futbol-2.jpg' style='max-width:600px;' \/><\/p>\n<div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\">Forbes M\u00e9xico<\/a>.<br \/>\n <a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/concacaf-cambia-eliminatoria-mundialista-mexico-jugaria-menos-partidos\/\">Concacaf cambia eliminatoria mundialista; M\u00e9xico jugar\u00eda menos partidos<\/a><\/p>\n<div><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/cdn.forbes.com.mx\/2019\/03\/seleccion-mexicana-futbol-2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" style=\"margin-bottom: 15px;\" srcset=\"https:\/\/cdn.forbes.com.mx\/2019\/03\/seleccion-mexicana-futbol-2.jpg 1280w, https:\/\/cdn.forbes.com.mx\/2019\/03\/seleccion-mexicana-futbol-2-300x169.jpg 300w, https:\/\/cdn.forbes.com.mx\/2019\/03\/seleccion-mexicana-futbol-2-768x432.jpg 768w, https:\/\/cdn.forbes.com.mx\/2019\/03\/seleccion-mexicana-futbol-2-1024x576.jpg 1024w, https:\/\/cdn.forbes.com.mx\/2019\/03\/seleccion-mexicana-futbol-2-640x360.jpg 640w, https:\/\/cdn.forbes.com.mx\/2019\/03\/seleccion-mexicana-futbol-2-320x180.jpg 320w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" data-full-size=\"https:\/\/cdn.forbes.com.mx\/2019\/03\/seleccion-mexicana-futbol-2.jpg\" data-caption=\"Foto: Notimex.\" data-description=\"\" \/><\/div>\n<p><strong>Notimex.-<\/strong> La Concacaf anunci\u00f3 el cambio de formato para la eliminatoria rumbo a la Copa del Mundo Qatar 2022.<\/p>\n<p>La reestructuraci\u00f3n de la eliminatoria se compondr\u00e1 de dos partes, las cuales se disputar\u00e1n de forma simult\u00e1nea; la primera ser\u00e1 el conocido hexagonal final, mismo que ser\u00e1 integrado por las seis mejores selecciones de la Concacaf de acuerdo al ranking de la FIFA posterior a junio de 2020.<\/p>\n<p>Esas seis representaciones, en las que se prev\u00e9 la presencia de M\u00e9xico, Estados Unidos y Costa Rica, si la l\u00f3gica impera, pelear\u00e1n por tres boletos directos al Mundial qatar\u00ed.<\/p>\n<p>Los tres primeros lugares del Hexagonal, que se jugar\u00e1 a partidos de ida y vuelta durante las fechas FIFA de septiembre, octubre y noviembre de 2020 y marzo y septiembre de 2021, pr\u00e1cticamente asegurar\u00e1n su presencia en la Copa del Mundo, mientras que el cuarto sitio deber\u00e1 esperar para seguir en la lucha por asistir a Qatar 2022.<\/p>\n<p><strong>Te podr\u00eda interesar: <a title=\"Messi celebra su cumplea\u00f1os ganando por hora lo que a ti te tomar\u00eda a\u00f1os\" href=\"https:\/\/www.forbes.com.mx\/messi-celebra-su-cumpleanos-ganando-por-hora-lo-que-a-ti-te-tomaria-anos\/\" target=\"_blank\" rel=\"noopener noreferrer\">Messi celebra su cumplea\u00f1os ganando por hora lo que a ti te tomar\u00eda a\u00f1os<\/a><\/strong><\/p>\n<p>La segunda parte de la eliminatoria mundialista se jugar\u00e1 de la siguiente forma: Las 29 mejores selecciones de la Concacaf seg\u00fan el ranking FIFA posterior a junio 2020 integrar\u00e1n esta eliminatoria, que primero se disputar\u00e1 en fase de grupos.<\/p>\n<p>Las 29 asociaciones miembro participantes ser\u00e1n divididas en ocho grupos, cinco de cuatro selecciones y tres grupos de tres. Despu\u00e9s de disputar la Fase de Grupos, con partidos de ida y vuelta durante las fechas FIFA de septiembre, octubre y noviembre de 2020, el primer lugar en cada uno de los ocho grupos se clasificar\u00e1 para la fase de eliminaci\u00f3n directa.<\/p>\n<p>En la eliminaci\u00f3n directa, con duelos de ida y vuelta, que arranca desde los cuartos de final, para luego jugarse las semifinales y la final, se desarrollar\u00e1 durante las fechas FIFA de marzo, junio y septiembre de 2021.<\/p>\n<p>El ganador de la fase de eliminaci\u00f3n directa se enfrentar\u00e1 al cuarto clasificado del Hexagonal, en octubre de 2021, para determinar al representante de Concacaf en el repechaje intercontinental de la FIFA.<\/p>\n<p>El vencedor de la serie de ida y vuelta entre el cuarto lugar del Hexagonal y el ganador de la segunda parte de eliminatoria, que jugar\u00e1n 29 selecciones, pelear\u00e1 por un cupo a Qatar 2022 contra una selecci\u00f3n de Asia, Ocean\u00eda o de la Conmebol, seg\u00fan determine la FIFA m\u00e1s adelante.<\/p>\n<p>Con esta modificaci\u00f3n, M\u00e9xico tendr\u00e1 menos partidos en su camino mundialista, pues antes lleg\u00f3 a disputar hasta dos rondas previas antes de encarar el Hexagonal.<\/p>\n<p><strong>Te recomendamos:\u00a0<\/strong><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"8RSbLiNtkb\">\n<p><a href=\"https:\/\/www.forbes.com.mx\/estos-son-los-jugadores-de-futbol-mejor-pagados-del-mundo-en-2019\/\">Estos son los jugadores de futbol mejor pagados del mundo en 2019<\/a><\/p>\n<\/blockquote>\n<p><iframe class=\"embed-responsive-item\"  title=\"&#8220;Estos son los jugadores de futbol mejor pagados del mundo en 2019&#8221; &#8212; Forbes M\u00e9xico\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.forbes.com.mx\/estos-son-los-jugadores-de-futbol-mejor-pagados-del-mundo-en-2019\/embed\/#?secret=8RSbLiNtkb\" data-secret=\"8RSbLiNtkb\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/concacaf-cambia-eliminatoria-mundialista-mexico-jugaria-menos-partidos\/\">Concacaf cambia eliminatoria mundialista; M\u00e9xico jugar\u00eda menos partidos<\/a><br \/>\n<a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/author\/forbes-staff\/\">Forbes Staff<\/a><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Forbes M\u00e9xico. Concacaf cambia eliminatoria mundialista; M\u00e9xico jugar\u00eda menos partidos Notimex.- La Concacaf anunci\u00f3 el cambio de formato para la eliminatoria rumbo a la Copa del Mundo Qatar 2022. La reestructuraci\u00f3n de la eliminatoria se compondr\u00e1 de dos partes, las cuales se disputar\u00e1n de forma simult\u00e1nea; la primera ser\u00e1 el conocido hexagonal final, mismo que [&hellip;]<\/p>","protected":false},"author":91,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4634","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/comments?post=4634"}],"version-history":[{"count":0,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4634\/revisions"}],"wp:attachment":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/media?parent=4634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/categories?post=4634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/tags?post=4634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}