{"id":4644,"date":"2019-07-10T14:11:27","date_gmt":"2019-07-10T19:11:27","guid":{"rendered":"https:\/\/enlacescorporativos.com\/?p=4644"},"modified":"2019-07-10T14:11:27","modified_gmt":"2019-07-10T19:11:27","slug":"expertos-brasilenos-se-unen-para-combatir-sargazo-en-playas-mexicanas","status":"publish","type":"post","link":"https:\/\/enlacescorporativos.com\/en\/2019\/07\/10\/expertos-brasilenos-se-unen-para-combatir-sargazo-en-playas-mexicanas\/","title":{"rendered":"Expertos brasile\u00f1os se unen para combatir sargazo en playas mexicanas"},"content":{"rendered":"<div><img src='https:\/\/cdn.forbes.com.mx\/2019\/07\/90624062.jpg' style='max-width:600px;' \/><\/p>\n<div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\">Forbes M\u00e9xico<\/a>.<br \/>\n <a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/expertos-brasilenos-se-unen-para-combatir-sargazo-en-playas-mexicanas\/\">Expertos brasile\u00f1os se unen para combatir sargazo en playas mexicanas<\/a><\/p>\n<div><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/cdn.forbes.com.mx\/2019\/07\/90624062.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" style=\"margin-bottom: 15px;\" srcset=\"https:\/\/cdn.forbes.com.mx\/2019\/07\/90624062.jpg 1280w, https:\/\/cdn.forbes.com.mx\/2019\/07\/90624062-300x169.jpg 300w, https:\/\/cdn.forbes.com.mx\/2019\/07\/90624062-768x432.jpg 768w, https:\/\/cdn.forbes.com.mx\/2019\/07\/90624062-1024x576.jpg 1024w, https:\/\/cdn.forbes.com.mx\/2019\/07\/90624062-600x338.jpg 600w, https:\/\/cdn.forbes.com.mx\/2019\/07\/90624062-200x113.jpg 200w, https:\/\/cdn.forbes.com.mx\/2019\/07\/90624062-640x360.jpg 640w, https:\/\/cdn.forbes.com.mx\/2019\/07\/90624062-320x180.jpg 320w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" data-full-size=\"https:\/\/cdn.forbes.com.mx\/2019\/07\/90624062.jpg\" data-caption=\"La red de Monitoreo del Sargazo Canc\u00fan, inform\u00f3 que la pr\u00f3xima semana se espera el arribo de sargazo a las costas de Quintana Roo, que afectar\u00e1 principalmente la l\u00ednea litoral de 260 kil\u00f3metros de costa entre Tulum y Xcalak.  Foto: Nancy Lim\u00f3m \/ Notimex 2019 06 24\" data-description=\"\" \/><\/div>\n<p>Acad\u00e9micos y cient\u00edficos brasile\u00f1os se integrar\u00e1n a una mesa de trabajo con legisladores y autoridades mexicanas que buscan controlar la acumulaci\u00f3n de sargazo en playas del Caribe mexicano.<\/p>\n<p>El equipo brasile\u00f1o se integrar\u00e1 al Consejo T\u00e9cnico Asesor integrado por especialistas en la materia en Quintana Roo, por invitaci\u00f3n de Javier Alegre, presidente de la Comisi\u00f3n de Turismo de la C\u00e1mara de Diputados a trav\u00e9s de la embajada de Brasil en M\u00e9xico.<\/p>\n<p>Adem\u00e1s de colaborar, los brasile\u00f1os est\u00e1n interesados en dejar claro que la teor\u00eda que establece que el sargazo que llega a las playas mexicanas proviene de Brasil y que se forma debido al derramamiento de qu\u00edmicos en sus costas, detall\u00f3 el diputado del grupo parlamentario de Morena en entrevista con Forbes.<\/p>\n<p>\u201cHay m\u00e1s cosas que no se saben del sargazo que lo que si se sabe, lo que sabemos es que \u00a0crece al doble cuando se encuentra con aguas c\u00e1lidas y nutrientes que es en el caso del caribe mexicano (\u2026) Tuvimos un acercamiento con el embajador de Brasil que va a evitar cient\u00edficos y t\u00e9cnicos para aportar informaci\u00f3n en torno al argumento de que es en ese pa\u00eds donde se genera el crecimiento\u201d, detall\u00f3 Alegre.<\/p>\n<p>Este no ser\u00e1 el \u00fanico acercamiento internacional que se estar\u00e1 llevando a cabo desde el Congreso de la Uni\u00f3n en torno al problema del sargazo. Alegre se\u00f1al\u00f3 que se ha buscado a las autoridades de Texas y Florida para sensibilizar a las autoridades en torno a esta problem\u00e1tica.<\/p>\n<p>El legislador asegur\u00f3 que las medidas establecidas por Andr\u00e9s Manuel L\u00f3pez Obrador ara contener la llegada de esta alga a las costas mexicanas son las correctas.<\/p>\n<p>\u201cSi no podemos eliminar el sargazo, deber\u00edamos poder reducirlo, si sabemos que crece al doble cada 18 d\u00edas, hay que buscar recolectar el sargazo antes de que tenga este crecimiento exponencial m\u00e1s o menos a la altura de Chetumal con Belic\u201d, apunt\u00f3.<\/p>\n<p>Hasta mayo de este a\u00f1o se tenia contabilizado la llegada de un mill\u00f3n de toneladas de sargazo a las playas del Caribe Mexicano, que representan un aumento de 300% en comparaci\u00f3n al a\u00f1o pasado.<\/p>\n<p>El a\u00f1o pasado, los empresarios enfocados en el turismo de las costas de Quintana Roo erogaron alrededor de 80 millones de pesos para enfrentar el problema.<\/p>\n<p>De acuerdo con expertos, el fen\u00f3meno dura alrededor de cuatro meses pero debido al calentamiento global, \u00e9ste podr\u00eda durar m\u00e1s meses al tiempo.<\/p>\n<p><strong>Te recomendamos:\u00a0<\/strong><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"snQtvvzSwl\">\n<p><a href=\"https:\/\/www.forbes.com.mx\/el-sargazo-que-inunda-las-playas-podria-volverse-oro-rojo-para-el-pais\/\">El sargazo que inunda las playas podr\u00eda volverse &#8216;oro rojo&#8217; para el pa\u00eds<\/a><\/p>\n<\/blockquote>\n<p><iframe class=\"embed-responsive-item\"  title=\"&#8220;El sargazo que inunda las playas podr\u00eda volverse &#8216;oro rojo&#8217; para el pa\u00eds&#8221; &#8212; Forbes M\u00e9xico\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.forbes.com.mx\/el-sargazo-que-inunda-las-playas-podria-volverse-oro-rojo-para-el-pais\/embed\/#?secret=snQtvvzSwl\" data-secret=\"snQtvvzSwl\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/expertos-brasilenos-se-unen-para-combatir-sargazo-en-playas-mexicanas\/\">Expertos brasile\u00f1os se unen para combatir sargazo en playas mexicanas<\/a><br \/>\n<a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/author\/fernanda-navarro\/\">Mar\u00eda Fernanda Navarro<\/a><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Forbes M\u00e9xico. Expertos brasile\u00f1os se unen para combatir sargazo en playas mexicanas Acad\u00e9micos y cient\u00edficos brasile\u00f1os se integrar\u00e1n a una mesa de trabajo con legisladores y autoridades mexicanas que buscan controlar la acumulaci\u00f3n de sargazo en playas del Caribe mexicano. El equipo brasile\u00f1o se integrar\u00e1 al Consejo T\u00e9cnico Asesor integrado por especialistas en la materia [&hellip;]<\/p>","protected":false},"author":91,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4644","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/comments?post=4644"}],"version-history":[{"count":0,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4644\/revisions"}],"wp:attachment":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/media?parent=4644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/categories?post=4644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/tags?post=4644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}