{"id":4654,"date":"2019-07-10T14:56:14","date_gmt":"2019-07-10T19:56:14","guid":{"rendered":"https:\/\/enlacescorporativos.com\/?p=4654"},"modified":"2019-07-10T14:56:14","modified_gmt":"2019-07-10T19:56:14","slug":"el-futuro-es-femenino-participa-en-cartier-womens-iniciative","status":"publish","type":"post","link":"https:\/\/enlacescorporativos.com\/en\/2019\/07\/10\/el-futuro-es-femenino-participa-en-cartier-womens-iniciative\/","title":{"rendered":"El futuro es femenino: participa en Cartier Women\u2019s Iniciative"},"content":{"rendered":"<div><img src='https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women%C2%B4s-Iniciative-2020.jpg' style='max-width:600px;' \/><\/p>\n<div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\">Forbes M\u00e9xico<\/a>.<br \/>\n <a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/participa-en-cartier-womens-iniciative\/\">El futuro es femenino: participa en Cartier Women\u2019s Iniciative<\/a><\/p>\n<div><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" style=\"margin-bottom: 15px;\" srcset=\"https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020.jpg 1280w, https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-300x169.jpg 300w, https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-768x432.jpg 768w, https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-1024x576.jpg 1024w, https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-600x338.jpg 600w, https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-200x113.jpg 200w, https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-640x360.jpg 640w, https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-320x180.jpg 320w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" data-full-size=\"https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020.jpg\" data-caption=\"\" data-description=\"\" \/><\/div>\n<p><span style=\"font-weight: 400;\">\u00bfC\u00f3mo es el rostro de la mujer que cambiar\u00e1 el entorno emprendedor en 2020? Desde su creaci\u00f3n en 2006, Cartier, en mancuerna con McKinsey &amp; Company e INSEAD Business School, han logrado incentivar el desarrollo y liderazgo empresarial femenino desde su iniciativa Cartier Women\u2019s Iniciative, concurso global que el pasado mayo de 2019 galardon\u00f3 a la primer mexicana en su historia, Liza Velarde, cofundadora y CEO de Delee, quien fue seleccionada de entre 2,900 solicitantes de m\u00e1s de 142 pa\u00edses como ganadora para la regi\u00f3n de Am\u00e9rica Latina.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con el firme objetivo de alentar a todas las mujeres emprendedoras del mundo a resolver los retos globales contempor\u00e1neos, Cartier Women\u2019s Iniciative lanz\u00f3 recientemente su convocatoria 2020, que busca elegir a tres finalistas de siete regiones en el mundo: Am\u00e9rica Latina, Norteam\u00e9rica, Europa, \u00c1frica Subsahariana, Oriente Medio y Norte de \u00c1frica, Asia del Este, y Asia del Sur y Ocean\u00eda.<\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-575958 size-full lazyload\" src=\"https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-2.jpg\" alt=\"\" width=\"980\" height=\"653\" srcset=\"https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-2.jpg 980w, https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-2-300x200.jpg 300w, https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-2-768x512.jpg 768w, https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-2-600x400.jpg 600w, https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-2-200x133.jpg 200w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">As\u00ed, diversos proyectos y negocios con visi\u00f3n y compromiso social <a href=\"https:\/\/tinyurl.com\/y6actqfn\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #ff0000;\"><strong>podr\u00e1n participar<\/strong><\/span><\/a> bajo los siguientes criterios: \u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Ser un negocio <\/span><b>dise\u00f1ado para generar ingresos<\/b><span style=\"font-weight: 400;\">. Podr\u00e1n participar los negocios estructurados de modo que produzcan ganancias suficientes para respaldar sus operaciones y devolver alg\u00fan nivel de ingresos a sus propietarios.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Los proyectos deben tener<\/span><b> al menos un a\u00f1o generando ingresos<\/b><span style=\"font-weight: 400;\"> por las ventas de sus productos y\/o servicios, a partir de la fecha de la solicitud. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; No haber recaudado <\/span><b>m\u00e1s de dos millones de d\u00f3lares en fondos dilutivos<\/b><span style=\"font-weight: 400;\">. La iniciativa limita los fondos recaudados a esta cantidad para garantizar que las empresas seleccionadas se encuentren dentro de un rango de desarrollo similar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; Deben <\/span><b>tener entre uno y cinco a\u00f1os de operaciones autorizadas y\/o registradas<\/b><span style=\"font-weight: 400;\">. Esto con el fin de comprobar que sean negocios en la fase inicial de su desarrollo y crecimiento. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; <\/span><span style=\"font-weight: 400;\">Cumplir con al menos uno de los <\/span><b>Objetivos de Desarrollo Sostenible<\/b><span style=\"font-weight: 400;\"> establecido por la Organizaci\u00f3n de las Naciones Unidas. Estos son 17 objetivos globales establecidos por la Asamblea General de las Naciones Unidas en 2015 para cumplirse en 2030, los cuales abarcan una serie de temas de desarrollo social, econ\u00f3mico y ambiental.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8211; La posici\u00f3n de <\/span><b>liderazgo principal<\/b><span style=\"font-weight: 400;\"> de los negocios debe ser ocupada <\/span><b>por una mujer<\/b><span style=\"font-weight: 400;\">, ya sea en calidad de Director, Gerente General o CEO. A su vez, \u00e9sta debe ser due\u00f1a de una participaci\u00f3n significativa dentro de la empresa. La propiedad del negocio se eval\u00faa en funci\u00f3n de la posici\u00f3n del candidato con relaci\u00f3n a otras partes interesadas.<\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-575959 size-full lazyload\" src=\"https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-3.jpg\" alt=\"\" width=\"980\" height=\"653\" srcset=\"https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-3.jpg 980w, https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-3-300x200.jpg 300w, https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-3-768x512.jpg 768w, https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-3-600x400.jpg 600w, https:\/\/cdn.forbes.com.mx\/2019\/06\/Cartier-Women\u00b4s-Iniciative-2020-3-200x133.jpg 200w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">De las 21 empresarias que ser\u00e1n elegidas como finalistas, tras superar las rigurosas pruebas y procesos, \u00a0y que obtendr\u00e1n un premio de <strong>30,000 d\u00f3lares<\/strong> y capacitaci\u00f3n para su proyecto, se seleccionar\u00e1n \u00fanicamente a siete ganadoras, una para representar a cada regi\u00f3n, quienes recibir\u00e1n adicionalmente un premio de <strong>100,000 d\u00f3lares<\/strong>. Las aplicaciones para la edici\u00f3n 2020 ya est\u00e1n abiertas desde el 12 de junio y hasta el 14 de agosto. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es momento de representar todo el talento y liderazgo de la mujer contempor\u00e1nea, <\/span><span style=\"color: #ff0000;\"><strong><a style=\"color: #ff0000;\" href=\"https:\/\/tinyurl.com\/y6actqfn\" target=\"_blank\" rel=\"noopener noreferrer\">aqu\u00ed<\/a><\/strong><\/span><span style=\"font-weight: 400;\">. \u00a0<\/span><\/p>\n<p><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.forbes.com.mx\/forbes-life\/por-primera-vez-una-mexicana-gana-el-premio-cartier-womens-initiative\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>Tambi\u00e9n puede interesarte: Por primera vez una mexicana gana el premio Cartier Women\u2019s Initiative<\/b><\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/participa-en-cartier-womens-iniciative\/\">El futuro es femenino: participa en Cartier Women\u2019s Iniciative<\/a><br \/>\n<a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/author\/forbes-advertorial\/\">Forbes Advertorial<\/a><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Forbes M\u00e9xico. El futuro es femenino: participa en Cartier Women\u2019s Iniciative \u00bfC\u00f3mo es el rostro de la mujer que cambiar\u00e1 el entorno emprendedor en 2020? Desde su creaci\u00f3n en 2006, Cartier, en mancuerna con McKinsey &amp; Company e INSEAD Business School, han logrado incentivar el desarrollo y liderazgo empresarial femenino desde su iniciativa Cartier Women\u2019s [&hellip;]<\/p>","protected":false},"author":91,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4654","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/comments?post=4654"}],"version-history":[{"count":0,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4654\/revisions"}],"wp:attachment":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/media?parent=4654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/categories?post=4654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/tags?post=4654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}