{"id":4702,"date":"2019-07-11T08:16:54","date_gmt":"2019-07-11T13:16:54","guid":{"rendered":"https:\/\/enlacescorporativos.com\/?p=4702"},"modified":"2019-07-11T08:16:54","modified_gmt":"2019-07-11T13:16:54","slug":"beat-arrancara-operaciones-el-15-de-julio-en-mty-y-el-22-en-gdl","status":"publish","type":"post","link":"https:\/\/enlacescorporativos.com\/en\/2019\/07\/11\/beat-arrancara-operaciones-el-15-de-julio-en-mty-y-el-22-en-gdl\/","title":{"rendered":"Beat arrancar\u00e1 operaciones el 15 de julio en MTY y el 22 en GDL"},"content":{"rendered":"<div><img src='https:\/\/cdn.forbes.com.mx\/2019\/01\/beat_coming.jpg' style='max-width:600px;' \/><\/p>\n<div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\">Forbes M\u00e9xico<\/a>.<br \/>\n <a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/beat-arrancara-operaciones-el-15-de-julio-en-gdl-y-el-22-en-mty\/\">Beat arrancar\u00e1 operaciones el 15 de julio en MTY y el 22 en GDL<\/a><\/p>\n<div><img fetchpriority=\"high\" decoding=\"async\" width=\"3000\" height=\"2000\" src=\"https:\/\/cdn.forbes.com.mx\/2019\/01\/beat_coming.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" style=\"margin-bottom: 15px;\" srcset=\"https:\/\/cdn.forbes.com.mx\/2019\/01\/beat_coming.jpg 3000w, https:\/\/cdn.forbes.com.mx\/2019\/01\/beat_coming-300x200.jpg 300w, https:\/\/cdn.forbes.com.mx\/2019\/01\/beat_coming-768x512.jpg 768w, https:\/\/cdn.forbes.com.mx\/2019\/01\/beat_coming-1024x683.jpg 1024w\" sizes=\"(max-width: 3000px) 100vw, 3000px\" data-full-size=\"https:\/\/cdn.forbes.com.mx\/2019\/01\/beat_coming.jpg\" data-caption=\"\" data-description=\"\" \/><\/div>\n<p>Beat, la plataforma de movilidad de origen griego que encabeza Nikos Drandakis, ya tiene fecha oficial para que sus veh\u00edculos comiencen a rodar en otras dos ciudades del pa\u00eds, aparte de la ciudad de M\u00e9xico. El arranque en Monterrey ser\u00e1 el pr\u00f3ximo 15 de julio mientras que en Guadalajara ser\u00e1 el 22 del mismo mes.<\/p>\n<p><span style=\"font-weight: 400;\">&#8220;En Monterrey a partir del lunes 15 de julio los regiomontanos ya podr\u00e1n abrir la aplicaci\u00f3n de Beat y pedir un Beat por primera vez. Lo mismo pasar\u00e1 en Guadalajara el lunes 22 de julio, esas dos fechas son importantes en nuestros logros y metas en M\u00e9xico&#8221;, a<\/span>s\u00ed lo confirm\u00f3 para <em><strong>Forbes M\u00e9xico<\/strong>,<\/em> Carlos Lieja, director de operaciones de Beat M\u00e9xico.<\/p>\n<p>Lee tambi\u00e9n <a href=\"https:\/\/www.forbes.com.mx\/exclusiva-nikos-drandakis-el-griego-que-traera-la-competencia-de-uber-a-mexico\/\">Exclusiva | Nikos Drandakis, el griego que quiere ir contra Uber en M\u00e9xico<\/a><\/p>\n<p>Aunque la compa\u00f1\u00eda ya hab\u00eda anunciado sus planes de comenzar con la apertura de sus <em>Center Drivers<\/em> para poder capacitar a sus conductores en estas ciudades, las fechas de arranque de sus unidades aun estaban inciertas.<\/p>\n<p><span style=\"font-weight: 400;\">Beat comenz\u00f3 oficialmente a prestar sus servicios en febrero en la ciudad de M\u00e9xico, con lo que a decir del directivo, el ascenso en sus n\u00fameros la han llevado a ubicarse r\u00e1pidamente en el tercer puesto del mercado local, por debajo de Uber y Didi <\/span><span style=\"font-weight: 400;\">en escasos 5 meses.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;Las primeras 4 semanas estuvimos creciendo a una tasa del 60% semanal en viajes. Tan solo en el segundo mes de operaciones, hicimos siete veces m\u00e1s viajes de lo que hicimos el primer mes y el tercero han sido crecimientos acelerados de doble d\u00edgito. <\/span><span style=\"font-weight: 400;\">Y esto fue lo que nos llev\u00f3 a tomar la decisi\u00f3n de abrir Guadalajara y Monterrey en este mes de julio&#8221;, dijo.<\/span><\/p>\n<p>Sobre la entrada y apertura de mercado en estas dos ciudades, el directivo se\u00f1al\u00f3 que m\u00e1s que sea un reto, trabajar\u00e1n de la mano con las autoriades para que en el marco regulatoria de cada regi\u00f3n, Beat se apegue a las disposiciones y reglamentaciones que dicte cada zona.<\/p>\n<h3><strong>\u00bfSon regiones dif\u00edciles y complicadas?<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">&#8220;No s\u00e9 si sean mercados complicados, yo creo que la palabra que los describir\u00eda son mercados muy interesantes. Hay que recordar que la industria es muy nueva. Yo s\u00e9 que estamos muy acostumbrados a escuchar el tema de aplicaciones de movilidad\u00a0 pero es una industria nueva y como todo, va a tomar tiempo para que se acaben de afinar todos los detalles con respecto a la legislaci\u00f3n local. Lo que vamos a hacer es jugar con las reglas del juego que nos ponga la autoridad de cada estado, en cada ciudad y en ese sentido vamos a competir como una compa\u00f1\u00eda responsable en esta industria&#8221;, se\u00f1al\u00f3 Lieja.<\/span><\/p>\n<h3><strong>\u00bfC\u00f3mo van a trabajar con la autoridad?<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Cada mercado regula distinto la industria de la movilidad pero toda la autoridad lo hace con la mejor intenci\u00f3n de poner reglas en juego y de tener a todos los participantes del ecosistema contentos y de manera justa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lo que estamos haciendo es que tenemos un grupo de especialistas que habla con la autoridad, que entiende lo que est\u00e1n demandando. Nos sentamos en las mesas de negociaci\u00f3n, de participaci\u00f3n, junto con los otros jugadores del ecosistema y juntos estamos definiendo las reglas en las que no hay punto de discusi\u00f3n y nos estamos ateniendo a lo que nos propone la autoridad.<\/span><\/p>\n<h3><strong>Mercado Local<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Ya somos la aplicaci\u00f3n n\u00famero tres a nivel nacional, solo compitiendo en la Ciudad de M\u00e9xico. Imag\u00ednate lo que vamos a lograr una vez que abramos las plazas que tenemos pensadas con Guadalajara y Monterrey los pr\u00f3ximos d\u00edas de julio.<\/span><\/p>\n<h3><strong>\u00bfC\u00f3mo miden esta posici\u00f3n?<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Es en la actividad de usuarios semanales, no es en viajes ni en descargas, sino en la actividad de usuarios que es de donde sacamos esta informaci\u00f3n. Es un super indicativo que si sabes que est\u00e1n usando tu aplicaci\u00f3n es porque est\u00e1n pidiendo viajes.<\/span><\/p>\n<h3><strong>\u00bfAbajo de Uber y DiDi?<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">La lectura es correcta, y no solo es en la participaci\u00f3n del mercado en la Ciudad de M\u00e9xico, lo que estamos tratando de decir es que solo compitiendo en M\u00e9xico en la Ciudad este ranking ya es nacional. Somos la tercer aplicaci\u00f3n a nivel nacional y \u00fanicamente compitiendo en la Ciudad de M\u00e9xico, imag\u00ednate lo que nos espera con el crecimiento ahora que abramos m\u00e1s plazas en los siguientes meses.<\/span><\/p>\n<h3><strong>\u00bfSon rivales muy grandes, c\u00f3mo le van a hacer, cu\u00e1l es su arma?<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Google no fue el primer buscador, Facebook no fue la primera red social, no nos asusta no haber sido pioneros en la industria como lo fueron los otros competidores, \u00bfqu\u00e9 nos distingue a nosotros? que tenemos much\u00edsimo foco en Latinoam\u00e9rica a diferencia de los otros competidores. En Beat lo que tenemos es que somos especialistas en Latinoam\u00e9rica y queremos que ese sea nuestro principal diferenciador.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mejores precios, conocer mejor la ciudad, tener experiencias localizadas y dise\u00f1adas para pasajeros y conductores, entonces puede haber competidores norteamericanos o asi\u00e1ticos que quieran el mundo completo, nosotros no, queremos ser el primero en Latinoam\u00e9rica\u00a0 y nuestra aspiraci\u00f3n es ser la n\u00famero uno de movilidad.<\/span><\/p>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/beat-arrancara-operaciones-el-15-de-julio-en-gdl-y-el-22-en-mty\/\">Beat arrancar\u00e1 operaciones el 15 de julio en MTY y el 22 en GDL<\/a><br \/>\n<a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/author\/mauricio-hernandez\/\">Mauricio Hern\u00e1ndez Armenta<\/a><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Forbes M\u00e9xico. Beat arrancar\u00e1 operaciones el 15 de julio en MTY y el 22 en GDL Beat, la plataforma de movilidad de origen griego que encabeza Nikos Drandakis, ya tiene fecha oficial para que sus veh\u00edculos comiencen a rodar en otras dos ciudades del pa\u00eds, aparte de la ciudad de M\u00e9xico. El arranque en Monterrey [&hellip;]<\/p>","protected":false},"author":91,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4702","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/comments?post=4702"}],"version-history":[{"count":0,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4702\/revisions"}],"wp:attachment":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/media?parent=4702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/categories?post=4702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/tags?post=4702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}