{"id":4724,"date":"2019-07-11T11:02:42","date_gmt":"2019-07-11T16:02:42","guid":{"rendered":"https:\/\/enlacescorporativos.com\/?p=4724"},"modified":"2019-07-11T11:02:42","modified_gmt":"2019-07-11T16:02:42","slug":"claves-para-potenciar-el-liderazgo-de-mis-hijos","status":"publish","type":"post","link":"https:\/\/enlacescorporativos.com\/en\/2019\/07\/11\/claves-para-potenciar-el-liderazgo-de-mis-hijos\/","title":{"rendered":"Claves para potenciar el liderazgo de mis hijos"},"content":{"rendered":"<div><img src='https:\/\/cdn.forbes.com.mx\/2019\/06\/ni%C3%B1os.jpg1_.jpg' style='max-width:600px;' \/><\/p>\n<div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\">Forbes M\u00e9xico<\/a>.<br \/>\n <a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/claves-para-potenciar-el-liderazgo-de-mis-hijos\/\">Claves para potenciar el liderazgo de mis hijos<\/a><\/p>\n<div><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/cdn.forbes.com.mx\/2019\/06\/ni\u00f1os.jpg1_.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" style=\"margin-bottom: 15px;\" srcset=\"https:\/\/cdn.forbes.com.mx\/2019\/06\/ni\u00f1os.jpg1_.jpg 1280w, https:\/\/cdn.forbes.com.mx\/2019\/06\/ni\u00f1os.jpg1_-300x169.jpg 300w, https:\/\/cdn.forbes.com.mx\/2019\/06\/ni\u00f1os.jpg1_-768x432.jpg 768w, https:\/\/cdn.forbes.com.mx\/2019\/06\/ni\u00f1os.jpg1_-1024x576.jpg 1024w, https:\/\/cdn.forbes.com.mx\/2019\/06\/ni\u00f1os.jpg1_-600x338.jpg 600w, https:\/\/cdn.forbes.com.mx\/2019\/06\/ni\u00f1os.jpg1_-200x113.jpg 200w, https:\/\/cdn.forbes.com.mx\/2019\/06\/ni\u00f1os.jpg1_-640x360.jpg 640w, https:\/\/cdn.forbes.com.mx\/2019\/06\/ni\u00f1os.jpg1_-320x180.jpg 320w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" data-full-size=\"https:\/\/cdn.forbes.com.mx\/2019\/06\/ni\u00f1os.jpg1_.jpg\" data-caption=\"Foto: Pexels. \" data-description=\"\" \/><\/div>\n<p>Se levant\u00f3 de su asiento y dijo: Coach, mi hijo saca cinco en matem\u00e1ticas, \u00bfDebo ponerle un profesor particular?<\/p>\n<p>\u00bfEn qu\u00e9 saca diez? \u2013Coment\u00e9-<\/p>\n<p>No s\u00e9 -contest\u00f3 la madre-<\/p>\n<p>Pues quien tiene cinco es usted \u2013 le dije- y no por querer ayudar a su hijo, sino \u00bfpor no saber c\u00f3mo?<\/p>\n<p>El auditorio call\u00f3, no lo esperaban.<\/p>\n<p>Mire se\u00f1ora, el problema no son las matem\u00e1ticas, \u00bfQu\u00e9 edad tiene su hijo?<\/p>\n<p>12 a\u00f1os \u2013contest\u00f3-<\/p>\n<p>Y \u00bfdesde cu\u00e1ndo se le complican las matem\u00e1ticas? \u2013 pregunt\u00e9-<\/p>\n<p>Toda la vida \u2013dijo-<\/p>\n<p>\u00bfUsted cree que su hijo querr\u00e1 ser contador? \u2013 pregunt\u00e9-<\/p>\n<p>No, lo dudo, las odia \u2013 contest\u00f3-<\/p>\n<p>Vaya a buscar pues, donde est\u00e1n los dieces de su hijo, para saber c\u00f3mo orientarlo en lo que es bueno, pues ah\u00ed conseguir\u00e1 de manera mucho m\u00e1s f\u00e1cil el \u00e9xito en su vida.<\/p>\n<p>Se qued\u00f3 pensando en lo que le dije, y despu\u00e9s pregunt\u00f3: \u00bfentonces no le pongo profe de mate?<\/p>\n<p>Ay\u00fadele usted o su marido, pero no gaste en eso, es una mala inversi\u00f3n -le dije- \u00bfsi sabe por qu\u00e9, no?<\/p>\n<p>Se qued\u00f3 callada.<\/p>\n<p>\u00bfUsted gastar\u00eda en un profe de algo que no le gusta y en lo que jam\u00e1s se va a dedicar, porque lo odia, o preferir\u00eda invertir en algo para ser mejor en algo que posiblemente le dar\u00e1 de comer el d\u00eda de ma\u00f1ana?<\/p>\n<p>Conversaciones como esta tengo constantemente en mis conferencias. El mundo ha cambiado, ahora no basta con tener una carrera, estudiar y conseguir un trabajo. As\u00ed pues, como coach, te comparto otra conversaci\u00f3n y algunas preguntas interesantes:<\/p>\n<p>Le dije a mi hijo que estudiara lo que m\u00e1s le gustaba, y ya me arrepent\u00ed, dijo.<\/p>\n<p>\u00bfQue fue? Pregunt\u00e9<\/p>\n<p>M\u00fasica, contest\u00f3 el padre.<\/p>\n<p>\u00bfY qu\u00e9 piensa de ello?, pregunt\u00e9.<\/p>\n<p>El padre call\u00f3, e hizo un gesto de desagrado.<\/p>\n<p>Qu\u00e9 se va a morir de hambre\u2026 afirm\u00e9, mientras volte\u00e9 a ver las caras de los dem\u00e1s asistentes. Quienes se notaban emp\u00e1ticos al padre y a la situaci\u00f3n.<\/p>\n<p>\u00bfCu\u00e1ntos de ustedes, han pensado esto?, not\u00e9 c\u00f3mo muchos levantaban la mano, eran la mayor\u00eda. Y ped\u00ed que la dejaran levantada. \u00bfCu\u00e1ntos de ustedes lo afirman o aseguran sin saber si su hijo pueda triunfar en aquello que desea?<\/p>\n<p>Qu\u00e9 bueno que sus hijos no est\u00e1n aqu\u00ed, pues ser\u00eda una desgracia para ellos saber que sus padres no les tienen ni la m\u00ednima confianza en lo que desean, en sus capacidades o habilidades.<\/p>\n<p>Luego pregunt\u00e9: \u00bfCu\u00e1ntos de ustedes, hacen algo que no les gusta, no les llena y no les apasiona? \u00bfCu\u00e1ntos de ustedes han manipulado la cabeza de sus hijos para que ellos estudien otra cosa, o hagan otra cosa?<\/p>\n<p>El problema es que los confunden por \u201c<a href=\"https:\/\/www.forbes.com.mx\/que-tendrias-que-hacer-para-ser-un-gran-lider\/\">hacerlos responsables<\/a>\u201d de los miedos que como padres tienen. El manejo de escenarios les puede hacer sentido y responsabilidad, pero es m\u00e1s importante el construir seguridad y certeza en ellos.<\/p>\n<p>\u00bfQu\u00e9 tanto apoyas y descubres con ellos en donde est\u00e1n sus caminos de menor resistencia a la plenitud, a la riqueza, o al triunfo?<\/p>\n<p>Hablar con ellos te ser\u00e1 de ayuda, si deseas saber \u00bfqu\u00e9 es el triunfo, el \u00e9xito y la riqueza para ellos? Impulsar su liderazgo implica saber d\u00f3nde est\u00e1 su camino, y hacerle ver sus decisiones como propias, sabiendo las implicaciones que representan, pero no desconfiando de \u00e9l, sino apoy\u00e1ndole y construyendo su seguridad personal, pi\u00e9nsalo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Contacto:<\/strong><\/p>\n<p>Correo:\u00a0alexmeza00@gmail.com\u00a0\/\u00a0dir@impulsocoaching.com<\/p>\n<p>Twitter:\u00a0<a href=\"https:\/\/twitter.com\/coachalexmeza\" target=\"_blank\" rel=\"noopener noreferrer\">@coachalexmeza<\/a><\/p>\n<p>Facebook:\u00a0<a href=\"https:\/\/www.facebook.com\/ImpulsoHumanoMexico\" target=\"_blank\" rel=\"noopener noreferrer\">ImpulsoHumanoMexico<\/a><\/p>\n<p>P\u00e1gina web:\u00a0<a href=\"http:\/\/www.impulsocoaching.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Impulso Coaching<\/a><\/p>\n<p><em>Las opiniones expresadas son s\u00f3lo responsabilidad de sus autores y son completamente independientes de la postura y la l\u00ednea editorial de\u00a0<strong>Forbes M\u00e9xico.<\/strong><\/em><\/p>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/claves-para-potenciar-el-liderazgo-de-mis-hijos\/\">Claves para potenciar el liderazgo de mis hijos<\/a><br \/>\n<a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/author\/alejandro-meza\/\">Alejandro Meza<\/a><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Forbes M\u00e9xico. Claves para potenciar el liderazgo de mis hijos Se levant\u00f3 de su asiento y dijo: Coach, mi hijo saca cinco en matem\u00e1ticas, \u00bfDebo ponerle un profesor particular? \u00bfEn qu\u00e9 saca diez? \u2013Coment\u00e9- No s\u00e9 -contest\u00f3 la madre- Pues quien tiene cinco es usted \u2013 le dije- y no por querer ayudar a su [&hellip;]<\/p>","protected":false},"author":91,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4724","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/comments?post=4724"}],"version-history":[{"count":0,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4724\/revisions"}],"wp:attachment":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/media?parent=4724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/categories?post=4724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/tags?post=4724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}