{"id":4734,"date":"2019-07-11T12:11:25","date_gmt":"2019-07-11T17:11:25","guid":{"rendered":"https:\/\/enlacescorporativos.com\/?p=4734"},"modified":"2019-07-11T12:11:25","modified_gmt":"2019-07-11T17:11:25","slug":"el-teletrabajo-en-la-cuarta-revolucion-industrial","status":"publish","type":"post","link":"https:\/\/enlacescorporativos.com\/en\/2019\/07\/11\/el-teletrabajo-en-la-cuarta-revolucion-industrial\/","title":{"rendered":"El teletrabajo en la Cuarta Revoluci\u00f3n Industrial"},"content":{"rendered":"<div><img src='https:\/\/cdn.forbes.com.mx\/2018\/12\/reuters-joven-empleo-desempleo-trabajo.jpg' style='max-width:600px;' \/><\/p>\n<div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\">Forbes M\u00e9xico<\/a>.<br \/>\n <a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/el-teletrabajo-en-la-cuarta-revolucion-industrial\/\">El teletrabajo en la Cuarta Revoluci\u00f3n Industrial<\/a><\/p>\n<div><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/cdn.forbes.com.mx\/2018\/12\/reuters-joven-empleo-desempleo-trabajo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" style=\"margin-bottom: 15px;\" srcset=\"https:\/\/cdn.forbes.com.mx\/2018\/12\/reuters-joven-empleo-desempleo-trabajo.jpg 1280w, https:\/\/cdn.forbes.com.mx\/2018\/12\/reuters-joven-empleo-desempleo-trabajo-300x169.jpg 300w, https:\/\/cdn.forbes.com.mx\/2018\/12\/reuters-joven-empleo-desempleo-trabajo-768x432.jpg 768w, https:\/\/cdn.forbes.com.mx\/2018\/12\/reuters-joven-empleo-desempleo-trabajo-1024x576.jpg 1024w, https:\/\/cdn.forbes.com.mx\/2018\/12\/reuters-joven-empleo-desempleo-trabajo-640x360.jpg 640w, https:\/\/cdn.forbes.com.mx\/2018\/12\/reuters-joven-empleo-desempleo-trabajo-320x180.jpg 320w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" data-full-size=\"https:\/\/cdn.forbes.com.mx\/2018\/12\/reuters-joven-empleo-desempleo-trabajo.jpg\" data-caption=\"Foto: Reuters.\" data-description=\"\" \/><\/div>\n<p>En M\u00e9xico le estamos dando la bienvenida a una serie de reformas en materia laboral que presumen de que experimentaremos un cambio total del esquema que conocemos para el desarrollo de las relaciones laborales, sobre todo de las relaciones colectivas en las que los sujetos son los empleadores, las organizaciones sindicales y los trabajadores que las integran.<\/p>\n<p>As\u00ed mismo nos encontramos tambi\u00e9n en una etapa de transici\u00f3n en la impartici\u00f3n de justicia laboral y, como bien sabemos, estos cambios sumados a otros de car\u00e1cter sustantivo y adjetivo son derivados de una reforma a la norma laboral interna de nuestro pa\u00eds que comenz\u00f3 en febrero de 2017 tocando nuestra Carta Magna, y en mayo de este 2019 reformando preceptos de la Ley Federal de Trabajo, sin embargo estamos en espera de otro cambio m\u00e1s a integrar ahora proponiendo regular el \u201cteletrabajo\u201d.<\/p>\n<p>Tenemos claro que la evoluci\u00f3n de las normas de trabajo tiene que adaptarse a los nuevos modelos de producci\u00f3n, pero precisamente encontramos que nuestra legislaci\u00f3n en esta materia representada por la Ley Federal del Trabajo, a\u00fan contiene muchos conceptos propios de sistemas de producci\u00f3n de principios del siglo XX, aquellos que plante\u00f3 en su momento la teor\u00eda &#8220;Taylorista&#8221; que buscaba ante todo la mayor eficiencia en tiempo y procesos en el modelo productivo y que fue materializado por Henry Ford, creando el modelo &#8220;Fordista&#8221; que ten\u00eda como principal caracter\u00edstica la alta producci\u00f3n en serie logrando productos m\u00e1s accesibles para su consumo, luego al tener un alto inventario por vender y aun en bodegas se percataron de que el modelo no era a\u00fan perfecto, por lo que su competencia japonesa Toyota a finales de los a\u00f1os sesenta aposto por no pagar m\u00e1s altos costos de almacenaje e invertirlo mejor en desarrollo tecnol\u00f3gico y de calidad, pero para ello vend\u00eda y luego fabricaba, para lo que necesitaba flexibilidad en las relaciones de trabajo.<\/p>\n<p>Una muestra de avance para flexibilizar las relaciones de trabajo que busca estar acorde a los medios de producci\u00f3n actuales que cuentan con herramientas fruto de la tecnolog\u00eda y medios de comunicaci\u00f3n propias de la Cuarta Revoluci\u00f3n Industrial es la aprobaci\u00f3n de la Iniciativa de Decreto por parte del Senado para reformar algunos de los preceptos de la Ley Federal del Trabajo para regular <a href=\"https:\/\/www.forbes.com.mx\/los-empleos-del-futuro\/\" target=\"_blank\" rel=\"noopener noreferrer\">la figura del \u201cteletrabajo\u201d<\/a>, que la propia iniciativa define como \u201cLa forma de organizaci\u00f3n laboral que consiste\u00a0 en el desempe\u00f1o de actividades remuneradas, sin requerirse la presencia f\u00edsica del trabajador en un sitio espec\u00edfico de trabajo y utilizando como soporte las tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n para el contacto entre el trabajador y el empleador\u201d.<\/p>\n<p>Para regular esta figura y diferenciarla con la actividad que realizan algunas personas por cuenta propia o trabajadores aut\u00f3nomos, el legislador dentro de esta iniciativa hace ver en primer lugar que las herramientas de trabajo las debe de proporcionar el patr\u00f3n, que es la misma diferencia que encontramos entre una relaci\u00f3n laboral y una prestaci\u00f3n de servicios profesionales, en este caso las herramientas son desde el ordenador con el cual prestar\u00e1 su servicio el trabajador, hasta el m\u00f3dem o l\u00ednea de internet.<\/p>\n<p>Otro de los puntos que marcan la diferencia es la obligaci\u00f3n del patr\u00f3n a promover y fomentar el equilibrio e igualdad de remuneraciones, capacitaci\u00f3n y seguridad social, que son elementos a los que no tienen derecho quienes se dedican a la actividad por cuenta propia conocidos como \u201c<em>freelance<\/em>\u201d.<\/p>\n<p>A pesar de que este tipo de trabajo no ser\u00e1 dentro de las instalaciones del empleador, esta reforma tambi\u00e9n contempla algunas obligaciones relacionadas a la salud, seguridad y previsi\u00f3n social, obligaciones que podremos conocer m\u00e1s a fondo cuando, de aprobarse esta iniciativa por la C\u00e1mara de Diputados, sea llevada al Ejecutivo para su publicaci\u00f3n en el Diario Oficial de la Federaci\u00f3n y cobre vigencia al d\u00eda siguiente, toda vez que a partir de su entrada en vigor se contar\u00e1 con un a\u00f1o para la creaci\u00f3n de una Norma Oficial Mexicana que reglamente la figura del &#8220;teletrabajo&#8221; y se conforme una Red Nacional de Fomento al Teletrabajo.<\/p>\n<p>Sin duda es un acierto la b\u00fasqueda que hace la C\u00e1mara de Senadores para actualizar nuestra norma aunque sea solo un poco intentando acercarla a los nuevos sistemas de producci\u00f3n y de relaciones de trabajo, ya en muchas organizaciones es conocida y usada esta figura con \u00e9xito, y son muchas las ventajas que se reportan con su implementaci\u00f3n, tanto para los empleadores como lo es el ahorro en infraestructura, oficinas, consumo de energ\u00eda el\u00e9ctrica, mobiliario de oficina y su respectivo mantenimiento, como las ventajas para los trabajadores, como es la flexibilidad de horarios logrando con ello un mayor equilibrio entre la vida laboral y la vida familiar.<\/p>\n<p>Otra ventaja, sin duda, ser\u00e1 el innecesario desplazamiento a los centros de trabajo con lo que se logran dos cosas muy importantes, primero el ahorro econ\u00f3mico en medios de trasporte, as\u00ed como menores niveles de estr\u00e9s lo cual podr\u00eda traducirse en mayor productividad, y sin duda alguna reflejar\u00eda tambi\u00e9n un beneficio inmediato al ambiente.<\/p>\n<p>Deberemos de esperar algo de tiempo para su implementaci\u00f3n ya que a\u00fan se encuentra en espera de su aprobaci\u00f3n por la C\u00e1mara de Diputados, pero sin duda de aprobarse tendr\u00e1 un gran beneficio la implementaci\u00f3n del \u201cteletrabajo\u201d en M\u00e9xico, no solo beneficiar\u00e1 a los sujetos de las relaciones de trabajo que se puedan realizar con esta figura, sino ser\u00e1 un beneficio para todos al no tener la necesidad de encontrarnos a las ocho de la ma\u00f1ana en una ciudad tan ca\u00f3tica como la CDMX.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Contact<\/strong>:<\/p>\n<p>Correo:\u00a0valentequintanapineda@gmail.com<\/p>\n<p>LinkedIn:\u00a0<a href=\"https:\/\/www.linkedin.com\/in\/valente-quintana-5877b423\" target=\"_blank\" rel=\"noopener noreferrer\">valente-quintana<\/a><\/p>\n<p><em>Las opiniones expresadas son s\u00f3lo responsabilidad de sus autores y son completamente independientes de la postura y la l\u00ednea editorial de\u00a0<strong>Forbes M\u00e9xico.<\/strong><\/em><\/p>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/el-teletrabajo-en-la-cuarta-revolucion-industrial\/\">El teletrabajo en la Cuarta Revoluci\u00f3n Industrial<\/a><br \/>\n<a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/author\/valente-quintana\/\">Valente Quintana Pineda<\/a><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Forbes M\u00e9xico. El teletrabajo en la Cuarta Revoluci\u00f3n Industrial En M\u00e9xico le estamos dando la bienvenida a una serie de reformas en materia laboral que presumen de que experimentaremos un cambio total del esquema que conocemos para el desarrollo de las relaciones laborales, sobre todo de las relaciones colectivas en las que los sujetos son [&hellip;]<\/p>","protected":false},"author":91,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4734","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/comments?post=4734"}],"version-history":[{"count":0,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4734\/revisions"}],"wp:attachment":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/media?parent=4734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/categories?post=4734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/tags?post=4734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}