{"id":4738,"date":"2019-07-11T12:31:30","date_gmt":"2019-07-11T17:31:30","guid":{"rendered":"https:\/\/enlacescorporativos.com\/?p=4738"},"modified":"2019-07-11T12:31:30","modified_gmt":"2019-07-11T17:31:30","slug":"juez-niega-amparo-a-tribu-yaqui-en-contra-de-gasoducto-leonino","status":"publish","type":"post","link":"https:\/\/enlacescorporativos.com\/en\/2019\/07\/11\/juez-niega-amparo-a-tribu-yaqui-en-contra-de-gasoducto-leonino\/","title":{"rendered":"Juez niega amparo a tribu Yaqui en contra de gasoducto \u2018leonino\u2019"},"content":{"rendered":"<div><img src='https:\/\/cdn.forbes.com.mx\/2016\/03\/IENOVA5.jpg' style='max-width:600px;' \/><\/p>\n<div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\">Forbes M\u00e9xico<\/a>.<br \/>\n <a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/juez-niega-amparo-a-tribu-yaqui-en-contra-de-gasoducto-leonino\/\">Juez niega amparo a tribu Yaqui en contra de gasoducto &#8216;leonino&#8217;<\/a><\/p>\n<div><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"800\" src=\"https:\/\/cdn.forbes.com.mx\/2016\/03\/IENOVA5.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" style=\"margin-bottom: 15px;\" srcset=\"https:\/\/cdn.forbes.com.mx\/2016\/03\/IENOVA5.jpg 1280w, https:\/\/cdn.forbes.com.mx\/2016\/03\/IENOVA5-300x188.jpg 300w, https:\/\/cdn.forbes.com.mx\/2016\/03\/IENOVA5-768x480.jpg 768w, https:\/\/cdn.forbes.com.mx\/2016\/03\/IENOVA5-1024x640.jpg 1024w, https:\/\/cdn.forbes.com.mx\/2016\/03\/IENOVA5-640x400.jpg 640w, https:\/\/cdn.forbes.com.mx\/2016\/03\/IENOVA5-320x200.jpg 320w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" data-full-size=\"https:\/\/cdn.forbes.com.mx\/2016\/03\/IENOVA5.jpg\" data-caption=\"Gasoducto Sonora (Foto.IEnova).\" data-description=\"\" \/><\/div>\n<p>Una Juez federal neg\u00f3 el amparo a la tribu yaqui Loma de B\u00e1cum, opositora a un gasoducto de la empresa Infraestructura Energ\u00e9tica Nova (IEnova).<\/p>\n<p>&#8220;La juez ha determinado no otorgar el amparo de la justifica federal a este grupo, y sobresee el juicio, pues considera que las actividades de consulta se llevaron a cabo y en la que nosotros participamos fueron suficientes y que el consenso alcanzado fue necesario&#8221;, detallaron los representantes de los 8 pueblos de la tribu yaqui en un comunicado.<\/p>\n<p>Los pueblos celebraron que la juez escuch\u00f3 sus argumentos de la &#8220;gran mayor\u00eda de la gente&#8221; que particip\u00f3 en la consulta para la construcci\u00f3n del gasoducto.<\/p>\n<p>El gasoducto en conflicto Guaymas-El Oro tiene una longitud de 331 kil\u00f3metros y cruza los estados de Sonora y Sinaloa. Tiene una capacidad de 510 millones de pies c\u00fabicos de gas diarios. El proyecto requirir\u00f3 una inversi\u00f3n de 429 millones de d\u00f3lares (mdd).<\/p>\n<p>La obra inici\u00f3 operaciones en mayo de 2017, pero fue saboteada por una comunidad yaqui.<\/p>\n<p>Los 8 pueblos pidieron a sus compa\u00f1eros opositores a que trabajen en uni\u00f3n con el restro de la tribu yaqui para &#8220;empezar a recibir los beneficios&#8221; que les traer\u00eda el proyecto.<\/p>\n<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador y el director general de la Comisi\u00f3n Federal de Electricidad, Manuel Bartlett, han calificado al contrato de la obra como &#8216;leonino&#8217; por los cargos fijos que ha pagado la compa\u00f1\u00eda estatal, y por los que busca un reembolso por 842 mdd.<\/p>\n<p><em><strong>Lee tambi\u00e9n:\u00a0<a href=\"https:\/\/www.forbes.com.mx\/que-pelea-la-cfe-con-las-constructoras-de-los-gasoductos-leoninos\/\">\u00bfQu\u00e9 pelea la CFE con las constructoras de los gasoductos &amp;#8216;leoninos&amp;#8217;?<\/a><\/strong><\/em><\/p>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/juez-niega-amparo-a-tribu-yaqui-en-contra-de-gasoducto-leonino\/\">Juez niega amparo a tribu Yaqui en contra de gasoducto &#8216;leonino&#8217;<\/a><br \/>\n<a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/author\/arturo-solis\/\">Arturo Sol\u00eds<\/a><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Forbes M\u00e9xico. Juez niega amparo a tribu Yaqui en contra de gasoducto &#8216;leonino&#8217; Una Juez federal neg\u00f3 el amparo a la tribu yaqui Loma de B\u00e1cum, opositora a un gasoducto de la empresa Infraestructura Energ\u00e9tica Nova (IEnova). &#8220;La juez ha determinado no otorgar el amparo de la justifica federal a este grupo, y sobresee el [&hellip;]<\/p>","protected":false},"author":91,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4738","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/comments?post=4738"}],"version-history":[{"count":0,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4738\/revisions"}],"wp:attachment":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/media?parent=4738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/categories?post=4738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/tags?post=4738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}