{"id":4746,"date":"2019-07-11T13:31:49","date_gmt":"2019-07-11T18:31:49","guid":{"rendered":"https:\/\/enlacescorporativos.com\/?p=4746"},"modified":"2019-07-11T13:31:49","modified_gmt":"2019-07-11T18:31:49","slug":"el-avance-global-de-las-inversiones-responsables","status":"publish","type":"post","link":"https:\/\/enlacescorporativos.com\/en\/2019\/07\/11\/el-avance-global-de-las-inversiones-responsables\/","title":{"rendered":"El avance global de las inversiones responsables"},"content":{"rendered":"<div><img src='https:\/\/cdn.forbes.com.mx\/2018\/10\/inversion-reuters.jpg' style='max-width:600px;' \/><\/p>\n<div>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\">Forbes M\u00e9xico<\/a>.<br \/>\n <a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/el-avance-global-de-las-inversiones-responsables\/\">El avance global de las inversiones responsables<\/a><\/p>\n<div><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/cdn.forbes.com.mx\/2018\/10\/inversion-reuters.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" style=\"margin-bottom: 15px;\" srcset=\"https:\/\/cdn.forbes.com.mx\/2018\/10\/inversion-reuters.jpg 1280w, https:\/\/cdn.forbes.com.mx\/2018\/10\/inversion-reuters-300x169.jpg 300w, https:\/\/cdn.forbes.com.mx\/2018\/10\/inversion-reuters-768x432.jpg 768w, https:\/\/cdn.forbes.com.mx\/2018\/10\/inversion-reuters-1024x576.jpg 1024w, https:\/\/cdn.forbes.com.mx\/2018\/10\/inversion-reuters-640x360.jpg 640w, https:\/\/cdn.forbes.com.mx\/2018\/10\/inversion-reuters-320x180.jpg 320w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" data-full-size=\"https:\/\/cdn.forbes.com.mx\/2018\/10\/inversion-reuters.jpg\" data-caption=\"Foto: Reuters.\" data-description=\"\" \/><\/div>\n<p><strong>Por Gema Sacrist\u00e1n*<\/strong><\/p>\n<p>Cuando en enero de 2004 Kofi Annan escribi\u00f3 a cincuenta CEO de las m\u00e1s grandes instituciones financieras del mundo, no pod\u00eda imaginar el impacto global de su convocatoria. El entonces secretario general de la ONU les invitaba a unirse a la iniciativa del Banco Mundial para introducir manejos financieros responsables e integrar los factores ASG (ambientales, sociales y de gobernanza) en los mercados de capitales.<\/p>\n<p>Annan tampoco pod\u00eda imaginar que las siglas ASG estar\u00edan en boca de todos solo unos a\u00f1os m\u00e1s tarde junto a otras m\u00e1s, ODS, que corresponden a los Objetivos de Desarrollo Sostenible. Este conjunto de 17 metas fue formulado por las Naciones Unidas en 2015 como hoja de ruta para un mundo m\u00e1s sostenible.<\/p>\n<p>Hoy en d\u00eda, invertir con criterios ASG implica considerar el impacto social y\/o medioambiental y no solo la rentabilidad financiera, cuestiones demasiado cr\u00edticas como para ser ignoradas. Para tener una idea de su dimensi\u00f3n recordemos que los activos gestionados por fondos que incorporan una visi\u00f3n socialmente responsable alcanzan los 30,7 billones de d\u00f3lares en todo el mundo. Esto equivale a dos veces el PIB de Estados Unidos y es un monto diez veces mayor que en 2006, seg\u00fan los \u00faltimos datos publicados por la Global Sustainable Investment Alliance.<\/p>\n<p>Si aplicamos una visi\u00f3n m\u00e1s amplia y medimos todos los activos financieros que siguen las directrices que, tras aquella reuni\u00f3n de Kofi Annan, se cristalizaron al formularse los Principios de la Inversi\u00f3n Responsable, entonces el volumen supera los 86 billones de d\u00f3lares. Esta cifra equivale a cinco veces el PIB de Estados Unidos.<\/p>\n<p>Las finanzas responsables florecieron cuando eran m\u00e1s necesarias: poco despu\u00e9s de la crisis financiera de 2008. Su empuje ha venido dado por inversores cada vez m\u00e1s conscientes y exigentes, como Larry Fink, fundador y CEO de BlackRock, que en su misiva \u201cPurpose &amp; Profit\u201d (Prop\u00f3sito y Beneficio) argumenta, \u201cprop\u00f3sito empresarial\u201d y \u201cbeneficio\u201d son ahora dos conceptos inseparables, de ah\u00ed que \u2013dice\u2013 \u201ces m\u00e1s importante que nunca desarrollar estrategias a largo plazo que impulsen crecimiento y sostenibilidad\u201d. BlackRock es uno de los mayores inversores del mundo: gestiona casi siete billones de d\u00f3lares. A los inversionistas les siguen reguladores, supervisores, organizaciones internacionales y cada vez m\u00e1s empresas.<\/p>\n<p>Invertir con criterios ASG implica aunar el an\u00e1lisis financiero con el impacto sostenible. La realidad es que, a largo plazo, respetar principios sostenibles y responsables ayuda a alcanzar objetivos econ\u00f3micos empresariales. Ya lo se\u00f1alaba en 2005 el libro Who Cares Wins, otra iniciativa de Kofi Annan, donde por primera vez se acu\u00f1\u00f3 el t\u00e9rmino ASG. Su autor, Ivo Knoepfel, fue uno de los impulsores del conocido \u00edndice internacional Dow Jones Sustainability (DJS) al que tantas compa\u00f1\u00edas aspiran a integrarse.<\/p>\n<p>Todo esto es lo que ha impulsado el desarrollo de un mercado financiero sostenible con actores de distinta \u00edndole, desde bancos de desarrollo a estados, municipalidades, empresas p\u00fablicas y privadas. Europa y Estados Unidos son los mercados que est\u00e1n liderando la tendencia, pero en Am\u00e9rica Latina tambi\u00e9n se est\u00e1n haciendo cosas interesantes.<\/p>\n<p>La Bolsa de Brasil B3 (antigua Bovespa) no solo fue la primera del mundo que en 2004 se adhiri\u00f3 al Pacto Mundial, sino que fue la primera de un pa\u00eds emergente en firmar los Principios de Inversi\u00f3n Responsable y en lanzar un \u00edndice de sostenibilidad (2005); fue adem\u00e1s una de las cinco fundadoras en 2012 de la Plataforma de Bolsas Sostenibles impulsada por la ONU para promover la adopci\u00f3n de pr\u00e1cticas en materia de reporte sobre los factores ASG. Esta plataforma tambi\u00e9n integra hoy a los mercados de valores de Colombia, Argentina, Chile, Per\u00fa, M\u00e9xico, Ecuador, Costa Rica, Jamaica y Panam\u00e1.<\/p>\n<p>Varios pa\u00edses de la regi\u00f3n, como M\u00e9xico, Brasil, Chile y Argentina, cuentan ya con \u00edndices de sostenibilidad. Varias compa\u00f1\u00edas regionales han aprobado con nota los ex\u00e1menes para su integraci\u00f3n en \u00edndice Dow Jones Sustainability y en el FTSE4Good de Londres. En cuanto a renta fija, los bonos sociales y sostenibles est\u00e1n despegando. En bonos verdes, aunque en 2018 la regi\u00f3n no fue muy activa, ya acumula operaciones por 84.000 millones de d\u00f3lares, con Brasil y M\u00e9xico como emisores m\u00e1s activos.<\/p>\n<p>Del mismo modo, Per\u00fa, Chile, Argentina Brasil y M\u00e9xico han desarrollado sus propias gu\u00edas y recomendaciones sobre emisiones de bonos verdes. La Bolsa de Panam\u00e1 se ha convertido en la primera de Am\u00e9rica Latina que acoger\u00e1 la negociaci\u00f3n de bonos verdes al adherirse a Climate Bonds Initiative (CBI), una organizaci\u00f3n internacional que impulsa soluciones financieras para el cambio clim\u00e1tico y de la que ya forman parte Borsa Italiana (Italia), Deutsch B\u00f6rse (Alemania), Luxemburg Green Exchange (Luxemburgo), Nasdaq Norway (Noruega), Swiss Six Exchange (Suiza) y Taipei Exchange (China). Todo se est\u00e1 preparando para nuevas operaciones, seg\u00fan apunta la propia CBI.<\/p>\n<p>Sin duda, queda mucho por hacer. La ONU calcula que cumplir con los ODS requiere una inversi\u00f3n de entre cinco y siete billones de d\u00f3lares al a\u00f1o, para lo cual se ha identificado una brecha de 2,5 billones de d\u00f3lares en pa\u00edses en desarrollo. La brecha anual de financiaci\u00f3n en Am\u00e9rica Latina y el Caribe se calcula en 170.000 millones de d\u00f3lares anuales, 3% del PIB de toda la regi\u00f3n.<\/p>\n<p>Hay que seguir trabajando sin caer en la complacencia. Aunque es justo que reconozcamos que, adem\u00e1s de Kofi Annan, seguramente tampoco nosotros hubi\u00e9ramos imaginado entonces que las siglas ODS y ASG iban a estar tan presentes en nuestras vidas o en nuestras operaciones financieras.<\/p>\n<p>BID Invest abord\u00f3 estos temas en la Semana de la Sostenibilidad, el foro de negocios sostenibles m\u00e1s reconocido en Am\u00e9rica Latina y el Caribe, que se celebr\u00f3 del 24 al 28 de junio en la Ciudad de Panam\u00e1.<\/p>\n<p>*<strong>Directora General de Negocio de BID Invest<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>Las opiniones expresadas son s\u00f3lo responsabilidad de sus autores y son completamente independientes de la postura y la l\u00ednea editorial de\u00a0<strong>Forbes M\u00e9xico<\/strong>.<\/em><\/p>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/el-avance-global-de-las-inversiones-responsables\/\">El avance global de las inversiones responsables<\/a><br \/>\n<a rel=\"nofollow\" href=\"https:\/\/www.forbes.com.mx\/author\/invitado-forbes\/\">Invitado Forbes<\/a><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Forbes M\u00e9xico. El avance global de las inversiones responsables Por Gema Sacrist\u00e1n* Cuando en enero de 2004 Kofi Annan escribi\u00f3 a cincuenta CEO de las m\u00e1s grandes instituciones financieras del mundo, no pod\u00eda imaginar el impacto global de su convocatoria. El entonces secretario general de la ONU les invitaba a unirse a la iniciativa del [&hellip;]<\/p>","protected":false},"author":91,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4746","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/comments?post=4746"}],"version-history":[{"count":0,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/posts\/4746\/revisions"}],"wp:attachment":[{"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/media?parent=4746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/categories?post=4746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enlacescorporativos.com\/en\/wp-json\/wp\/v2\/tags?post=4746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}